{"id":157,"date":"2023-11-22T12:29:19","date_gmt":"2023-11-22T11:29:19","guid":{"rendered":"http:\/\/francefaucardage.com\/?page_id=157"},"modified":"2024-03-16T10:19:54","modified_gmt":"2024-03-16T09:19:54","slug":"plantes-subaquatiques-plantes-invasives-algues","status":"publish","type":"page","link":"https:\/\/francefaucardage.com\/index.php\/plantes-subaquatiques-plantes-invasives-algues\/","title":{"rendered":"Plantes subaquatiques, plantes invasives, algues faut-il faucarder ?"},"content":{"rendered":"\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a58057c5c367&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a58057c5e1de&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a58057c5e1de\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"207\" src=\"https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Egeria_densa.jpeg\" alt=\"Egeria densa\" class=\"wp-image-207\" title=\"\" srcset=\"https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Egeria_densa.jpeg 800w, https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Egeria_densa-300x225.jpeg 300w, https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Egeria_densa-768x576.jpeg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"752\" data-id=\"114\" src=\"https:\/\/francefaucardage.com\/wp-content\/uploads\/2023\/07\/Jussie_rampante_Montpon_Chandos_17-1024x752.jpg\" alt=\"\" class=\"wp-image-114\" title=\"\" srcset=\"https:\/\/francefaucardage.com\/wp-content\/uploads\/2023\/07\/Jussie_rampante_Montpon_Chandos_17-1024x752.jpg 1024w, https:\/\/francefaucardage.com\/wp-content\/uploads\/2023\/07\/Jussie_rampante_Montpon_Chandos_17-300x220.jpg 300w, https:\/\/francefaucardage.com\/wp-content\/uploads\/2023\/07\/Jussie_rampante_Montpon_Chandos_17-768x564.jpg 768w, https:\/\/francefaucardage.com\/wp-content\/uploads\/2023\/07\/Jussie_rampante_Montpon_Chandos_17.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"567\" height=\"1000\" data-id=\"206\" src=\"https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Cleaned-Illustration_Myriophyllum_spicatum.jpg\" alt=\"\" class=\"wp-image-206\" title=\"\" srcset=\"https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Cleaned-Illustration_Myriophyllum_spicatum.jpg 567w, https:\/\/francefaucardage.com\/wp-content\/uploads\/2024\/01\/Cleaned-Illustration_Myriophyllum_spicatum-170x300.jpg 170w\" sizes=\"auto, (max-width: 567px) 100vw, 567px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Identifier les v\u00e9g\u00e9taux pr\u00e9sents dans un lac, \u00e9tang, une pi\u00e8ce d&rsquo;eau, une rivi\u00e8re est la premi\u00e8re \u00e9tape pour aborder sa gestion raisonn\u00e9e :<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Le Nymph\u00e9a blanc (Nymphaea alba)<\/strong> : Commun\u00e9ment appel\u00e9 n\u00e9nuphar, il est enracin\u00e9 dans le fond vaseux des eaux dormantes, avec des feuilles en forme de c\u0153ur arrondi et une fleur \u00e9clatante de plus de quarante p\u00e9tales.<\/li>\n\n\n\n<li><strong>Le Nuphar jaune (Nuphar lutea)<\/strong> : Ressemble au n\u00e9nuphar blanc mais avec des feuilles plus ovales et une fleur jaune moins grande.<\/li>\n\n\n\n<li><strong>La Mor\u00e8ne ou Petit n\u00e9nuphar (Hydrocharis morsus-ranae)<\/strong> : Reconnaissable par ses petites feuilles flottantes vert bronze en forme de c\u0153ur et ses fleurs m\u00e2les pr\u00e9sentant un c\u0153ur jaune et trois p\u00e9tales blancs.<\/li>\n\n\n\n<li><strong>La Sagittaire \u00e0 feuilles en fl\u00e8che (Sagittaria sagittifolia)<\/strong> : Feuilles a\u00e9riennes en forme de fl\u00e8ches et fleurs blanches avec une tache violac\u00e9e \u00e0 la base.<\/li>\n\n\n\n<li><strong>Le Fl\u00fbteau nageant (Luronium natans)<\/strong> : Petites feuilles flottantes ovales et trinerv\u00e9es, avec des fleurs blanches et jaunes \u00e0 la base.<\/li>\n\n\n\n<li><strong>Le Plantain d\u2019eau (Alisma plantago-aquatica)<\/strong> : Grande plante enracin\u00e9e dans la vase, avec des feuilles ovales, lanc\u00e9ol\u00e9es et pointues, et des fleurs blanches ou l\u00e9g\u00e8rement ros\u00e9es.<\/li>\n\n\n\n<li><strong>Les Potamots (Potamogeton sp.)<\/strong> : Plantes \u00e0 feuilles flottantes ou submerg\u00e9es et aux fleurs verd\u00e2tres en \u00e9pis p\u00e9doncul\u00e9s.<\/li>\n\n\n\n<li><strong>Les Callitriches (Callitriche sp.)<\/strong> : Plantes fr\u00e9quentes dans les mares, les foss\u00e9s et les parties calmes des rivi\u00e8res et ruisseaux, formant des herbiers denses.<\/li>\n\n\n\n<li><strong>Les Lentilles d\u2019eau<\/strong> : Regroupements de feuilles minuscules flottant librement \u00e0 la surface.<\/li>\n\n\n\n<li><strong>Les Renoncules (Ranunculus sp.)<\/strong> : Fleurs blanches au c\u0153ur jaune avec cinq p\u00e9tales, et feuilles flottantes classiques.<\/li>\n\n\n\n<li><strong>La Glyc\u00e9rie flottante (Glyceria fluitans)<\/strong> : Gramin\u00e9e qui peut d\u00e9passer le m\u00e8tre, fr\u00e9quente dans les eaux stagnantes et faiblement courantes.<\/li>\n\n\n\n<li><strong>Le Cornifle nageant (Ceratophyllum demersum)<\/strong> : Plante submerg\u00e9e enracin\u00e9e dans les fonds vaseux, avec des feuilles vert fonc\u00e9, rigides, verticill\u00e9es et divis\u00e9es en minces segments dent\u00e9s.<\/li>\n\n\n\n<li><strong>Les Myriophylles (Myriophyllum sp.)<\/strong> : Feuilles rappelant celles du cornifle mais moins robustes et avec des segments minces non dent\u00e9s.<\/li>\n\n\n\n<li><strong>L\u2019Hottonie des marais (Hottonia palustris)<\/strong> : Plante remarquable au printemps avec ses grappes de fleurs blanches ou rose p\u00e2le au c\u0153ur orang\u00e9 et ses feuilles tr\u00e8s finement d\u00e9coup\u00e9es.<\/li>\n\n\n\n<li><strong>La Renou\u00e9e amphibie (Polygonum amphibium)<\/strong> : Plante aquatique avec des feuilles flottantes oblongues et pointues et des fleurs sous forme d\u2019\u00e9pis roses.<\/li>\n\n\n\n<li><strong>Le Millepertuis des marais (Hypericum elodes)<\/strong> : Petites feuilles oppos\u00e9es duveteuses et gris\u00e2tres, avec des fleurs jaunes p\u00e2les sous forme de petites cloches.<\/li>\n\n\n\n<li><strong>Les Utriculaires (Utricularia sp.)<\/strong> : Plantes carnivores sans racines, avec des feuilles classiques finement divis\u00e9es et des feuilles en forme d\u2019outres servant de pi\u00e8ges.<\/li>\n\n\n\n<li><strong>Les Plantes Invasives<\/strong> : Comme le Myriophylle du Br\u00e9sil (Myriophyllum brasiliense) et les Jussies (Ludwigia sp.), qui posent des probl\u00e8mes \u00e9cologiques et \u00e9conomiques.<\/li>\n\n\n\n<li><strong>Les \u00c9lod\u00e9es<\/strong> : Plantes toujours immerg\u00e9es, avec des feuilles souvent verticill\u00e9es par 3.<\/li>\n<\/ol>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Identifier les v\u00e9g\u00e9taux pr\u00e9sents dans un lac, \u00e9tang, une pi\u00e8ce d&rsquo;eau, une rivi\u00e8re est la premi\u00e8re \u00e9tape pour aborder sa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":33,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-157","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/pages\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":3,"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/pages\/157\/revisions"}],"predecessor-version":[{"id":311,"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/pages\/157\/revisions\/311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/media\/33"}],"wp:attachment":[{"href":"https:\/\/francefaucardage.com\/index.php\/wp-json\/wp\/v2\/media?parent=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}